{"id":10001259,"date":"2023-05-10T22:32:55","date_gmt":"2023-05-10T22:32:55","guid":{"rendered":"https:\/\/vip.sportsengine.com\/athens\/?post_type=tribe_events&#038;p=151"},"modified":"2025-08-12T15:26:24","modified_gmt":"2025-08-12T15:26:24","slug":"eagles-hockey-youth-registration-deadline","status":"publish","type":"tribe_events","link":"https:\/\/vip.sportsengine.com\/athens\/event\/eagles-hockey-youth-registration-deadline\/2028-12-29\/","title":{"rendered":"Eagles Hockey Youth Registration Deadline"},"content":{"rendered":"<p>Spark is a 9 hole, social league organized to be casual and fun, with a touch of friendly competition.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Spark is a 9 hole, social league organized to be casual and fun, with a touch of friendly competition. &nbsp;<\/p>\n","protected":false},"author":55,"featured_media":0,"template":"","meta":{"ghostkit_customizer_options":"","ghostkit_custom_css":"","ghostkit_custom_js_head":"","ghostkit_custom_js_foot":"","ghostkit_typography":"","_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","_EventEndDate":"2028-12-29 23:59:59","_EventStartDate":"2028-12-29 00:00:00","_EventURL":"","footnotes":""},"tags":[20],"tribe_events_cat":[16],"class_list":["post-10001259","tribe_events","type-tribe_events","status-publish","tag-test-tag","tribe_events_cat-test-category","cat_test-category","tribe-recurring-event","tribe-recurring-event-parent","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Eagles Hockey Youth Registration Deadline - Athens Demo Site<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vip.sportsengine.com\/athens\/event\/eagles-hockey-youth-registration-deadline\/2028-12-29\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eagles Hockey Youth Registration Deadline - Athens Demo Site\" \/>\n<meta property=\"og:description\" content=\"Spark is a 9 hole, social league organized to be casual and fun, with a touch of friendly competition. &nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vip.sportsengine.com\/athens\/event\/eagles-hockey-youth-registration-deadline\/2028-12-29\/\" \/>\n<meta property=\"og:site_name\" content=\"Athens Demo Site\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-12T15:26:24+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vip.sportsengine.com\\\/athens\\\/event\\\/eagles-hockey-youth-registration-deadline\\\/2028-12-29\\\/\",\"url\":\"https:\\\/\\\/vip.sportsengine.com\\\/athens\\\/event\\\/eagles-hockey-youth-registration-deadline\\\/2028-12-29\\\/\",\"name\":\"Eagles Hockey Youth Registration Deadline - Athens Demo Site\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vip.sportsengine.com\\\/athens\\\/#website\"},\"datePublished\":\"2023-05-10T22:32:55+00:00\",\"dateModified\":\"2025-08-12T15:26:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vip.sportsengine.com\\\/athens\\\/event\\\/eagles-hockey-youth-registration-deadline\\\/2028-12-29\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vip.sportsengine.com\\\/athens\\\/event\\\/eagles-hockey-youth-registration-deadline\\\/2028-12-29\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vip.sportsengine.com\\\/athens\\\/event\\\/eagles-hockey-youth-registration-deadline\\\/2028-12-29\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/vip.sportsengine.com\\\/athens\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Events\",\"item\":\"https:\\\/\\\/vip.sportsengine.com\\\/athens\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Eagles Hockey Youth Registration Deadline\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vip.sportsengine.com\\\/athens\\\/#website\",\"url\":\"https:\\\/\\\/vip.sportsengine.com\\\/athens\\\/\",\"name\":\"Athens Demo Site\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/vip.sportsengine.com\\\/athens\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vip.sportsengine.com\\\/athens\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vip.sportsengine.com\\\/athens\\\/#organization\",\"name\":\"Athens Demo Site\",\"url\":\"https:\\\/\\\/vip.sportsengine.com\\\/athens\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/vip.sportsengine.com\\\/athens\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/vip.sportsengine.com\\\/athens\\\/wp-content\\\/uploads\\\/sites\\\/105\\\/2023\\\/01\\\/Eagles_logo_horiz2.png\",\"contentUrl\":\"https:\\\/\\\/vip.sportsengine.com\\\/athens\\\/wp-content\\\/uploads\\\/sites\\\/105\\\/2023\\\/01\\\/Eagles_logo_horiz2.png\",\"width\":1445,\"height\":440,\"caption\":\"Athens Demo Site\"},\"image\":{\"@id\":\"https:\\\/\\\/vip.sportsengine.com\\\/athens\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Eagles Hockey Youth Registration Deadline - Athens Demo Site","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vip.sportsengine.com\/athens\/event\/eagles-hockey-youth-registration-deadline\/2028-12-29\/","og_locale":"en_US","og_type":"article","og_title":"Eagles Hockey Youth Registration Deadline - Athens Demo Site","og_description":"Spark is a 9 hole, social league organized to be casual and fun, with a touch of friendly competition. &nbsp;","og_url":"https:\/\/vip.sportsengine.com\/athens\/event\/eagles-hockey-youth-registration-deadline\/2028-12-29\/","og_site_name":"Athens Demo Site","article_modified_time":"2025-08-12T15:26:24+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/vip.sportsengine.com\/athens\/event\/eagles-hockey-youth-registration-deadline\/2028-12-29\/","url":"https:\/\/vip.sportsengine.com\/athens\/event\/eagles-hockey-youth-registration-deadline\/2028-12-29\/","name":"Eagles Hockey Youth Registration Deadline - Athens Demo Site","isPartOf":{"@id":"https:\/\/vip.sportsengine.com\/athens\/#website"},"datePublished":"2023-05-10T22:32:55+00:00","dateModified":"2025-08-12T15:26:24+00:00","breadcrumb":{"@id":"https:\/\/vip.sportsengine.com\/athens\/event\/eagles-hockey-youth-registration-deadline\/2028-12-29\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vip.sportsengine.com\/athens\/event\/eagles-hockey-youth-registration-deadline\/2028-12-29\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/vip.sportsengine.com\/athens\/event\/eagles-hockey-youth-registration-deadline\/2028-12-29\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/vip.sportsengine.com\/athens\/"},{"@type":"ListItem","position":2,"name":"Events","item":"https:\/\/vip.sportsengine.com\/athens\/events\/"},{"@type":"ListItem","position":3,"name":"Eagles Hockey Youth Registration Deadline"}]},{"@type":"WebSite","@id":"https:\/\/vip.sportsengine.com\/athens\/#website","url":"https:\/\/vip.sportsengine.com\/athens\/","name":"Athens Demo Site","description":"","publisher":{"@id":"https:\/\/vip.sportsengine.com\/athens\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vip.sportsengine.com\/athens\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/vip.sportsengine.com\/athens\/#organization","name":"Athens Demo Site","url":"https:\/\/vip.sportsengine.com\/athens\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/vip.sportsengine.com\/athens\/#\/schema\/logo\/image\/","url":"https:\/\/vip.sportsengine.com\/athens\/wp-content\/uploads\/sites\/105\/2023\/01\/Eagles_logo_horiz2.png","contentUrl":"https:\/\/vip.sportsengine.com\/athens\/wp-content\/uploads\/sites\/105\/2023\/01\/Eagles_logo_horiz2.png","width":1445,"height":440,"caption":"Athens Demo Site"},"image":{"@id":"https:\/\/vip.sportsengine.com\/athens\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/vip.nbcsportsnext.com\/athens\/event\/eagles-hockey-youth-registration-deadline\/2028-12-29\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Eagles Hockey Youth Registration Deadline","url":"http:\/\/vip.sportsengine.com\/athens\/event\/eagles-hockey-youth-registration-deadline\/2028-12-29\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/vip.sportsengine.com\/athens\/event\/eagles-hockey-youth-registration-deadline\/2028-12-29\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Uncategorized","author":[{"@type":"Person","name":"Sean McGrath"}],"creator":["Sean McGrath"],"publisher":{"@type":"Organization","name":"Athens Demo Site","logo":""},"keywords":["test tag"],"dateCreated":"2023-05-10T22:32:55Z","datePublished":"2023-05-10T22:32:55Z","dateModified":"2025-08-12T15:26:24Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Eagles Hockey Youth Registration Deadline\",\"url\":\"http:\\\/\\\/vip.sportsengine.com\\\/athens\\\/event\\\/eagles-hockey-youth-registration-deadline\\\/2028-12-29\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/vip.sportsengine.com\\\/athens\\\/event\\\/eagles-hockey-youth-registration-deadline\\\/2028-12-29\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Uncategorized\",\"author\":[{\"@type\":\"Person\",\"name\":\"Sean McGrath\"}],\"creator\":[\"Sean McGrath\"],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Athens Demo Site\",\"logo\":\"\"},\"keywords\":[\"test tag\"],\"dateCreated\":\"2023-05-10T22:32:55Z\",\"datePublished\":\"2023-05-10T22:32:55Z\",\"dateModified\":\"2025-08-12T15:26:24Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/vip.nbcsportsnext.com\/p.js"},"rkv_fs_custom_sources":{"event_venue":null,"event_series":"","event_organizer":""},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/vip.sportsengine.com\/athens\/wp-json\/wp\/v2\/tribe_events\/10001259","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vip.sportsengine.com\/athens\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/vip.sportsengine.com\/athens\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/vip.sportsengine.com\/athens\/wp-json\/wp\/v2\/users\/55"}],"version-history":[{"count":0,"href":"https:\/\/vip.sportsengine.com\/athens\/wp-json\/wp\/v2\/tribe_events\/10001259\/revisions"}],"wp:attachment":[{"href":"https:\/\/vip.sportsengine.com\/athens\/wp-json\/wp\/v2\/media?parent=10001259"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vip.sportsengine.com\/athens\/wp-json\/wp\/v2\/tags?post=10001259"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/vip.sportsengine.com\/athens\/wp-json\/wp\/v2\/tribe_events_cat?post=10001259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}